{"id":6617,"date":"2025-08-24T21:10:38","date_gmt":"2025-08-24T20:10:38","guid":{"rendered":"https:\/\/www.mexiko-mexico.org\/fotos\/Becal-Campeche-Iglesia-Nuestra-Senora-natividad.jpg"},"modified":"2025-08-24T21:10:38","modified_gmt":"2025-08-24T20:10:38","slug":"becal-campeche-iglesia-nuestra-senora-natividad-2","status":"inherit","type":"attachment","link":"https:\/\/www.mexiko-mexico.org\/en\/becal-campeche-iglesia-nuestra-senora-natividad-2\/","title":{"rendered":"Becal-Campeche-Iglesia-Nuestra- Senora-natividad"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":""},"estado":[],"municipio":[],"ort":[],"class_list":["post-6617","attachment","type-attachment","status-inherit","entry","has-post-thumbnail"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.mexiko-mexico.org\/fotos\/Becal-Campeche-Iglesia-Nuestra-Senora-natividad.jpg' data-lbwps-width=\"1920\" data-lbwps-height=\"1280\" data-lbwps-srcsmall=\"https:\/\/www.mexiko-mexico.org\/fotos\/Becal-Campeche-Iglesia-Nuestra-Senora-natividad-390x260.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"810\" height=\"540\" src=\"https:\/\/www.mexiko-mexico.org\/fotos\/Becal-Campeche-Iglesia-Nuestra-Senora-natividad-810x540.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.mexiko-mexico.org\/fotos\/Becal-Campeche-Iglesia-Nuestra-Senora-natividad-810x540.jpg 810w, https:\/\/www.mexiko-mexico.org\/fotos\/Becal-Campeche-Iglesia-Nuestra-Senora-natividad-390x260.jpg 390w, https:\/\/www.mexiko-mexico.org\/fotos\/Becal-Campeche-Iglesia-Nuestra-Senora-natividad-1536x1024.jpg 1536w, https:\/\/www.mexiko-mexico.org\/fotos\/Becal-Campeche-Iglesia-Nuestra-Senora-natividad-600x400.jpg 600w, https:\/\/www.mexiko-mexico.org\/fotos\/Becal-Campeche-Iglesia-Nuestra-Senora-natividad.jpg 1920w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1920,"height":1280,"file":"Becal-Campeche-Iglesia-Nuestra-Senora-natividad.jpg","filesize":459196,"sizes":{"medium":{"file":"Becal-Campeche-Iglesia-Nuestra-Senora-natividad-810x540.jpg","width":810,"height":540,"filesize":129157,"mime_type":"image\/jpeg","source_url":"https:\/\/www.mexiko-mexico.org\/fotos\/Becal-Campeche-Iglesia-Nuestra-Senora-natividad-810x540.jpg"},"thumbnail":{"file":"Becal-Campeche-Iglesia-Nuestra-Senora-natividad-390x260.jpg","width":390,"height":260,"filesize":58987,"mime_type":"image\/jpeg","source_url":"https:\/\/www.mexiko-mexico.org\/fotos\/Becal-Campeche-Iglesia-Nuestra-Senora-natividad-390x260.jpg"},"1536x1536":{"file":"Becal-Campeche-Iglesia-Nuestra-Senora-natividad-1536x1024.jpg","width":1536,"height":1024,"filesize":338256,"mime_type":"image\/jpeg","source_url":"https:\/\/www.mexiko-mexico.org\/fotos\/Becal-Campeche-Iglesia-Nuestra-Senora-natividad-1536x1024.jpg"},"mini-thumbnail":{"file":"Becal-Campeche-Iglesia-Nuestra-Senora-natividad-75x75.jpg","width":75,"height":75,"filesize":36074,"mime_type":"image\/jpeg","source_url":"https:\/\/www.mexiko-mexico.org\/fotos\/Becal-Campeche-Iglesia-Nuestra-Senora-natividad-75x75.jpg"},"team-member":{"file":"Becal-Campeche-Iglesia-Nuestra-Senora-natividad-600x600.jpg","width":600,"height":600,"filesize":112385,"mime_type":"image\/jpeg","source_url":"https:\/\/www.mexiko-mexico.org\/fotos\/Becal-Campeche-Iglesia-Nuestra-Senora-natividad-600x600.jpg"},"gb-block-post-grid-landscape":{"file":"Becal-Campeche-Iglesia-Nuestra-Senora-natividad-600x400.jpg","width":600,"height":400,"filesize":87546,"mime_type":"image\/jpeg","source_url":"https:\/\/www.mexiko-mexico.org\/fotos\/Becal-Campeche-Iglesia-Nuestra-Senora-natividad-600x400.jpg"},"gb-block-post-grid-square":{"file":"Becal-Campeche-Iglesia-Nuestra-Senora-natividad-600x600.jpg","width":600,"height":600,"filesize":112385,"mime_type":"image\/jpeg","source_url":"https:\/\/www.mexiko-mexico.org\/fotos\/Becal-Campeche-Iglesia-Nuestra-Senora-natividad-600x600.jpg"},"full":{"file":"Becal-Campeche-Iglesia-Nuestra-Senora-natividad.jpg","width":1920,"height":1280,"mime_type":"image\/jpeg","source_url":"https:\/\/www.mexiko-mexico.org\/fotos\/Becal-Campeche-Iglesia-Nuestra-Senora-natividad.jpg"}},"image_meta":{"aperture":"2.8","credit":"Simon Feiertag","camera":"NIKON D850","caption":"","created_timestamp":"1634161874","copyright":"Simon Feiertag","focal_length":"24","iso":"64","shutter_speed":"0.0003125","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.mexiko-mexico.org\/fotos\/Becal-Campeche-Iglesia-Nuestra-Senora-natividad.jpg","filename":"Becal-Campeche-Iglesia-Nuestra-Senora-natividad.jpg","filesize":459196,"_links":{"self":[{"href":"https:\/\/www.mexiko-mexico.org\/en\/wp-json\/wp\/v2\/media\/6617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mexiko-mexico.org\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.mexiko-mexico.org\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.mexiko-mexico.org\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mexiko-mexico.org\/en\/wp-json\/wp\/v2\/comments?post=6617"}],"wp:term":[{"taxonomy":"estado","embeddable":true,"href":"https:\/\/www.mexiko-mexico.org\/en\/wp-json\/wp\/v2\/estado?post=6617"},{"taxonomy":"municipio","embeddable":true,"href":"https:\/\/www.mexiko-mexico.org\/en\/wp-json\/wp\/v2\/municipio?post=6617"},{"taxonomy":"ort","embeddable":true,"href":"https:\/\/www.mexiko-mexico.org\/en\/wp-json\/wp\/v2\/ort?post=6617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}